{"id":9,"count":3,"description":"","link":"https:\/\/buanaindonesia.co.id\/62\/category\/nad\/aceh-selatan\/","name":"Aceh Selatan","slug":"aceh-selatan","taxonomy":"category","parent":2,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/buanaindonesia.co.id\/aceh\/category\/nad\/aceh-selatan\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceh Selatan Arsip - berita62.id\" \/>\n<meta property=\"og:url\" content=\"https:\/\/buanaindonesia.co.id\/aceh\/category\/nad\/aceh-selatan\/\" \/>\n<meta property=\"og:site_name\" content=\"berita62.id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/buanaindonesia.co.id\/62\/#website\",\"url\":\"https:\/\/buanaindonesia.co.id\/62\/\",\"name\":\"berita62.id\",\"description\":\"HOAK ITU BUKAN KITA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/buanaindonesia.co.id\/62\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"id-ID\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/buanaindonesia.co.id\/aceh\/category\/nad\/aceh-selatan\/#webpage\",\"url\":\"https:\/\/buanaindonesia.co.id\/aceh\/category\/nad\/aceh-selatan\/\",\"name\":\"Aceh Selatan Arsip - berita62.id\",\"isPartOf\":{\"@id\":\"https:\/\/buanaindonesia.co.id\/62\/#website\"},\"inLanguage\":\"id-ID\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/buanaindonesia.co.id\/62\/wp-json\/wp\/v2\/categories\/9"}],"collection":[{"href":"https:\/\/buanaindonesia.co.id\/62\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/buanaindonesia.co.id\/62\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/buanaindonesia.co.id\/62\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/buanaindonesia.co.id\/62\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}