{"id":5386,"count":3,"description":"","link":"https:\/\/buanaindonesia.co.id\/jabar\/tag\/gebyar-ramadhan\/","name":"Gebyar Ramadhan","slug":"gebyar-ramadhan","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/buanaindonesia.co.id\/jabar\/tag\/gebyar-ramadhan\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebyar Ramadhan Arsip - BUANAJABAR.CO.ID\" \/>\n<meta property=\"og:url\" content=\"https:\/\/buanaindonesia.co.id\/jabar\/tag\/gebyar-ramadhan\/\" \/>\n<meta property=\"og:site_name\" content=\"BUANAJABAR.CO.ID\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/buanaindonesia.co.id\/jabar\/#website\",\"url\":\"https:\/\/buanaindonesia.co.id\/jabar\/\",\"name\":\"BUANAJABAR.CO.ID\",\"description\":\"HOAK ITU BUKAN KITA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/buanaindonesia.co.id\/jabar\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"id-ID\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/buanaindonesia.co.id\/jabar\/tag\/gebyar-ramadhan\/#webpage\",\"url\":\"https:\/\/buanaindonesia.co.id\/jabar\/tag\/gebyar-ramadhan\/\",\"name\":\"Gebyar Ramadhan Arsip - BUANAJABAR.CO.ID\",\"isPartOf\":{\"@id\":\"https:\/\/buanaindonesia.co.id\/jabar\/#website\"},\"inLanguage\":\"id-ID\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/buanaindonesia.co.id\/jabar\/wp-json\/wp\/v2\/tags\/5386"}],"collection":[{"href":"https:\/\/buanaindonesia.co.id\/jabar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/buanaindonesia.co.id\/jabar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/buanaindonesia.co.id\/jabar\/wp-json\/wp\/v2\/posts?tags=5386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}